{"id":399,"date":"2025-12-22T17:19:05","date_gmt":"2025-12-22T16:19:05","guid":{"rendered":"https:\/\/les-amadeus.fr\/?p=399"},"modified":"2025-12-22T17:19:05","modified_gmt":"2025-12-22T16:19:05","slug":"joyeuses-fetes","status":"publish","type":"post","link":"https:\/\/les-amadeus.fr\/index.php\/2025\/12\/22\/joyeuses-fetes\/","title":{"rendered":"Joyeuses f\u00eates !"},"content":{"rendered":"\n<p>L&rsquo;ann\u00e9e 2025 se termine. La chorale vous souhaite de joyeuses f\u00eates et un bonne et heureuse ann\u00e9e 2026. <\/p>\n\n\n\n<p>On aura sans doute le plaisir de vous retrouver dans les prochains concerts de la nouvelle saison.<\/p>\n\n\n\n<p>@ bient\u00f4t.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/les-amadeus.fr\/wp-content\/uploads\/2025\/12\/Joyeuses-fetes-683x1024.png\" alt=\"\" class=\"wp-image-400\" srcset=\"https:\/\/les-amadeus.fr\/wp-content\/uploads\/2025\/12\/Joyeuses-fetes-683x1024.png 683w, https:\/\/les-amadeus.fr\/wp-content\/uploads\/2025\/12\/Joyeuses-fetes-200x300.png 200w, https:\/\/les-amadeus.fr\/wp-content\/uploads\/2025\/12\/Joyeuses-fetes-768x1152.png 768w, https:\/\/les-amadeus.fr\/wp-content\/uploads\/2025\/12\/Joyeuses-fetes-40x60.png 40w, https:\/\/les-amadeus.fr\/wp-content\/uploads\/2025\/12\/Joyeuses-fetes.png 1024w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;ann\u00e9e 2025 se termine. La chorale vous souhaite de joyeuses f\u00eates et un bonne et heureuse ann\u00e9e 2026. On aura sans doute le plaisir de vous retrouver dans les prochains concerts de la nouvelle saison. @ bient\u00f4t.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-399","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"views":129,"_links":{"self":[{"href":"https:\/\/les-amadeus.fr\/index.php\/wp-json\/wp\/v2\/posts\/399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/les-amadeus.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/les-amadeus.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/les-amadeus.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/les-amadeus.fr\/index.php\/wp-json\/wp\/v2\/comments?post=399"}],"version-history":[{"count":1,"href":"https:\/\/les-amadeus.fr\/index.php\/wp-json\/wp\/v2\/posts\/399\/revisions"}],"predecessor-version":[{"id":401,"href":"https:\/\/les-amadeus.fr\/index.php\/wp-json\/wp\/v2\/posts\/399\/revisions\/401"}],"wp:attachment":[{"href":"https:\/\/les-amadeus.fr\/index.php\/wp-json\/wp\/v2\/media?parent=399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/les-amadeus.fr\/index.php\/wp-json\/wp\/v2\/categories?post=399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/les-amadeus.fr\/index.php\/wp-json\/wp\/v2\/tags?post=399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}